{"id":46252,"date":"2024-12-02T01:00:19","date_gmt":"2024-12-02T01:00:19","guid":{"rendered":"https:\/\/feedontario.ca\/?post_type=news&#038;p=46252"},"modified":"2024-12-01T22:11:12","modified_gmt":"2024-12-01T22:11:12","slug":"les-banques-alimentaires-reduisent-leurs-services-face-a-une-demande-croissante","status":"publish","type":"news","link":"https:\/\/feedontario.ca\/fr\/news\/food-banks-cut-services-amid-surging-demand\/","title":{"rendered":"Les banques alimentaires r\u00e9duisent leurs services car la demande croissante d\u00e9passe les ressources."},"content":{"rendered":"<p><em>Un nouveau rapport de Feed Ontario r\u00e9v\u00e8le que 40% des banques alimentaires ont r\u00e9duit la quantit\u00e9 de nourriture qu'elles fournissent, et que la moiti\u00e9 d'entre elles ont \u00e9t\u00e9 forc\u00e9es de r\u00e9duire les services d'accompagnement dans un contexte de demande record et de p\u00e9nurie de ressources. Le rapport souligne que la crise de l'accessibilit\u00e9 financi\u00e8re et l'insuffisance des programmes de soutien gouvernementaux sont les moteurs de l'escalade de la demande.<\/em><\/p>\n<p>Feed Ontario a publi\u00e9 son<a href=\"https:\/\/feedontario.ca\/wp-content\/uploads\/2024\/11\/FEED_Ontario_HungerReport24.pdf\"> Rapport sur la faim 2024<\/a> qui r\u00e9v\u00e8le que la fr\u00e9quentation record des banques alimentaires a d\u00e9pass\u00e9 la capacit\u00e9 et les ressources du r\u00e9seau provincial de banques alimentaires. Selon le rapport publi\u00e9 plus t\u00f4t cette ann\u00e9e, plus d'un million de personnes ont eu recours aux banques alimentaires de l'Ontario, soit une augmentation de 25 % par rapport \u00e0 2023 et la huiti\u00e8me ann\u00e9e cons\u00e9cutive de croissance. Le rapport d\u00e9taille les tendances \u00e9conomiques, notamment les co\u00fbts \u00e9lev\u00e9s du logement et les emplois pr\u00e9caires, qui sont \u00e0 l'origine de cette augmentation. En plus de forcer un plus grand nombre de personnes \u00e0 se tourner vers les banques alimentaires pour obtenir de l'aide, la crise de l'accessibilit\u00e9 financi\u00e8re a fait en sorte que moins d'Ontariens sont en mesure de faire des dons ou de fournir le m\u00eame niveau de soutien que par le pass\u00e9.<\/p>\n<blockquote><p>\"Les gens ne se tournent vers les banques alimentaires qu'apr\u00e8s avoir \u00e9puis\u00e9 toutes les autres options - et pourtant, plus d'un million d'Ontariens ont encore besoin de notre aide\", d\u00e9clare Carolyn Stewart, directrice g\u00e9n\u00e9rale de Feed Ontario. \"Il s'agit du nombre de personnes le plus \u00e9lev\u00e9 jamais enregistr\u00e9, et ce, \u00e0 un moment o\u00f9 les dons diminuent, car de plus en plus de personnes n'ont plus les moyens de donner. En cons\u00e9quence, les banques alimentaires sont sollicit\u00e9es au-del\u00e0 de leur capacit\u00e9 et manquent de ressources \u00e0 un moment o\u00f9 les personnes et les familles en ont le plus besoin.<\/p><\/blockquote>\n<p>La publication du rapport est accompagn\u00e9e de<a href=\"https:\/\/youtu.be\/qUxGqU4D4Vo\"> une vid\u00e9o mettant en sc\u00e8ne des repr\u00e9sentants de banques alimentaires<\/a> de toute la province qui parlent des besoins accrus qu'ils constatent dans leurs communaut\u00e9s et des d\u00e9fis qu'ils doivent relever pour r\u00e9pondre \u00e0 cette demande. L'utilisation record des banques alimentaires est constante dans toute la province, chaque r\u00e9gion de l'Ontario ayant connu une augmentation \u00e0 deux chiffres de l'utilisation des banques alimentaires au cours de l'ann\u00e9e derni\u00e8re seulement.  Comme le dit Christine Clarke-Lefleur de Port Cares \u00e0 Port Colborne, \"Nous voyons des gens que nous avions l'habitude de voir il y a des ann\u00e9es, et des gens qui \u00e9taient des donateurs, qui doivent maintenant venir chercher de l'aide\".<\/p>\n<p>Le rapport 2024 sur la faim et la vid\u00e9o \u00e9voquent \u00e9galement les d\u00e9cisions difficiles que les banques alimentaires ont \u00e9t\u00e9 contraintes de prendre pour tenter de r\u00e9pondre \u00e0 une demande record et d'\u00e9tirer encore davantage des ressources d\u00e9j\u00e0 limit\u00e9es. Elles ont notamment r\u00e9duit la quantit\u00e9 de nourriture fournie aux personnes dans le besoin, supprim\u00e9 des programmes et des services d'accompagnement, et m\u00eame envisag\u00e9 la possibilit\u00e9 tr\u00e8s r\u00e9elle de devoir fermer leurs portes.<\/p>\n<blockquote><p>\"Les banques alimentaires font tout ce qu'elles peuvent pour garder leurs portes ouvertes et leurs \u00e9tag\u00e8res pleines, mais lorsque les donateurs commencent \u00e0 se transformer en clients, une situation impossible commence \u00e0 \u00e9merger\", d\u00e9clare M. Stewart. \"Les banques alimentaires n'ont pas les ressources n\u00e9cessaires pour r\u00e9pondre ad\u00e9quatement aux besoins de notre province. Par cons\u00e9quent, m\u00eame avec l'aide des banques alimentaires, des personnes et des familles souffrent de la faim.\"<\/p><\/blockquote>\n<p>Feed Ontario est tr\u00e8s clair dans son message : les banques alimentaires ne sont pas une solution \u00e0 la pauvret\u00e9 ou \u00e0 l'ins\u00e9curit\u00e9 alimentaire. Les gens se tournent vers les banques alimentaires parce que les politiques publiques et les programmes de soutien social les laissent tomber. Plus pr\u00e9cis\u00e9ment, le rapport souligne que les principaux facteurs d'utilisation des banques alimentaires sont les suivants :<\/p>\n<p><strong>Logement et co\u00fbt de la vie inabordables : <\/strong>Au cours des quatre derni\u00e8res ann\u00e9es, les banques alimentaires ont constat\u00e9 une augmentation de 80 % du nombre de m\u00e9nages qui louent leur logement, ainsi qu'une augmentation de 109 % du nombre de personnes qui vivent une forme quelconque de sans-abrisme (sans abri, dans un refuge d'urgence ou dans un refuge provincial).<\/p>\n<p><strong>Emploi pr\u00e9caire et opportunit\u00e9s d'emploi inad\u00e9quates :<\/strong> 1 visiteur de banque alimentaire sur 4 a un emploi, 42 % d'entre eux indiquant qu'ils gagnent le salaire minimum ou moins. Seulement 11 % des visiteurs de banques alimentaires interrog\u00e9s ont acc\u00e8s \u00e0 des cong\u00e9s de maladie pay\u00e9s.<\/p>\n<p><strong>L'\u00e9chec des programmes d'aide sociale :<\/strong> Pr\u00e8s de deux visiteurs de banques alimentaires sur trois sont des b\u00e9n\u00e9ficiaires de l'aide sociale. Le soutien financier fourni par Ontario Works et le Programme ontarien de soutien aux personnes handicap\u00e9es (POSPH) se situe respectivement \u00e0 66 % et 53 % sous le seuil de pauvret\u00e9.<\/p>\n<blockquote><p>\"Nous avons besoin d'une action imm\u00e9diate et audacieuse contre la pauvret\u00e9\", d\u00e9clare M. Stewart. \"Nous avons besoin que tous les niveaux de gouvernement accordent la priorit\u00e9 \u00e0 la r\u00e9duction de la pauvret\u00e9 et \u00e0 l'accessibilit\u00e9 financi\u00e8re, qu'ils fixent des objectifs clairs et qu'ils rendent des comptes. Nous voulons que le nombre de personnes ayant besoin des banques alimentaires diminue. Et nous voulons fermer nos portes parce que nos services ne sont pas n\u00e9cessaires, et non pas parce que la demande a augment\u00e9 au-del\u00e0 de notre capacit\u00e9 de service.<\/p><\/blockquote>\n<p>Feed Ontario pr\u00e9sente plusieurs recommandations politiques que le gouvernement de l'Ontario pourrait mettre en \u0153uvre d\u00e8s aujourd'hui pour commencer \u00e0 s'attaquer \u00e0 cette crise. Il s'agit notamment d'une approche nouvelle et plus audacieuse de sa strat\u00e9gie de r\u00e9duction de la pauvret\u00e9, de l'am\u00e9lioration d'Ontario Works et du Programme ontarien de soutien aux personnes handicap\u00e9es, notamment en s'attaquant aux obstacles auxquels les b\u00e9n\u00e9ficiaires du programme sont confront\u00e9s lorsqu'ils tentent de travailler, de l'am\u00e9lioration du droit du travail et de l'emploi en Ontario, et de nouveaux investissements dans le logement abordable.<\/p>\n<blockquote><p>\"Alors que nous continuons \u00e0 plaider pour des solutions de politique publique, les banques alimentaires ont un besoin urgent de votre aide aujourd'hui,\" dit Stewart. \"Si vous \u00eates en mesure de donner, votre don fera une diff\u00e9rence incroyable. Avec tant de personnes dans le besoin, votre soutien aidera \u00e0 garder les \u00e9tag\u00e8res des banques alimentaires pleines pour tous ceux qui ont besoin d'aide pendant les f\u00eates de fin d'ann\u00e9e\".<\/p><\/blockquote>\n<p>Les banques alimentaires ne sont pas financ\u00e9es par le gouvernement et d\u00e9pendent des dons pour garder leurs portes ouvertes et leurs \u00e9tag\u00e8res pleines. Feed Ontario demande \u00e0 tous ceux qui sont en mesure de donner pendant la p\u00e9riode des f\u00eates d'envisager de faire un don \u00e0 Feed Ontario et \u00e0 leur banque alimentaire locale. Pour chaque $1 donn\u00e9, Feed Ontario peut fournir deux repas \u00e0 une personne ou une famille dans le besoin.<\/p>\n<p><strong>Points forts et tendances du rapport sur la faim 2024<\/strong><\/p>\n<p><strong><u>Donn\u00e9es sur l'utilisation des banques alimentaires <\/u><\/strong><\/p>\n<ul>\n<li><strong>Individus uniques<\/strong>: Plus d'un million de personnes ont acc\u00e9d\u00e9 \u00e0 une banque alimentaire en Ontario entre le 1er avril 2023 et le 31 mars 2024, soit une augmentation de 25% par rapport \u00e0 l'ann\u00e9e derni\u00e8re et de 86% depuis 2019-2020.\n<ul>\n<li>Cela repr\u00e9sente 1 Ontarien sur 16 et plus que la population totale de la Nouvelle-\u00c9cosse.<\/li>\n<\/ul>\n<\/li>\n<li><strong>Visites :<\/strong> Les banques alimentaires de l'Ontario ont \u00e9t\u00e9 visit\u00e9es un total de 7 689 580 fois tout au long de l'ann\u00e9e, soit une augmentation de 31% par rapport \u00e0 l'ann\u00e9e derni\u00e8re et de 134% depuis 2019-2020.<\/li>\n<li><strong>Nouveaux utilisateurs :<\/strong> 2 visiteurs sur 5 n'avaient jamais acc\u00e9d\u00e9 \u00e0 une banque alimentaire auparavant, soit une augmentation de 43% depuis 2019-20.<\/li>\n<\/ul>\n<p><strong><u>Facteurs de fr\u00e9quentation des banques alimentaires<\/u><\/strong><\/p>\n<ul>\n<li><strong>Logement inabordable :<\/strong> 76% des visiteurs sont locataires et 9% sont en situation d'exclusion li\u00e9e au logement (logement pr\u00e9caire, sans abri, h\u00e9bergement d'urgence, etc.)<\/li>\n<li><strong>L'emploi pr\u00e9caire :<\/strong> Les visiteurs des banques alimentaires qui ont cit\u00e9 l'emploi comme principale source de revenus ont augment\u00e9 de 91% par rapport aux niveaux pr\u00e9-pand\u00e9miques et de 17% par rapport \u00e0 l'ann\u00e9e pr\u00e9c\u00e9dente.<\/li>\n<li><strong>Soutien social inad\u00e9quat<\/strong>: L'aide sociale demeure la principale source de revenu pour la majorit\u00e9 des visiteurs des banques alimentaires, 30% d\u00e9pendant d'OT et 29% d\u00e9pendant du POSPH.<\/li>\n<\/ul>\n<p><strong><u>Durabilit\u00e9 de la banque alimentaire<\/u><\/strong><\/p>\n<ul>\n<li><strong>R\u00e9duction de l'aide alimentaire :<\/strong> 38% des banques alimentaires ont d\u00e9clar\u00e9 avoir d\u00fb r\u00e9duire la quantit\u00e9 de nourriture qu'elles peuvent donner.<\/li>\n<li><strong>R\u00e9duction des mesures d'accompagnement :<\/strong> La moiti\u00e9 (50%) de toutes les banques alimentaires qui offraient un soutien global ont \u00e9t\u00e9 forc\u00e9es de couper ou de r\u00e9duire leur programme en raison de ressources insuffisantes.<\/li>\n<\/ul>\n<p>Les banques alimentaires ont besoin de votre aide. <a href=\"https:\/\/feedontario.ca\/fr\/rapport-sur-la-faim-2024\/\">En savoir plus sur le rapport sur la faim 2024<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"featured_media":46253,"template":"","class_list":["post-46252","news","type-news","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Food banks cut services as surging demand outpaces resources<\/title>\n<meta name=\"description\" content=\"A new report by Feed Ontario reveals that food banks are cutting service amid record-high demand and resource shortages.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/feedontario.ca\/fr\/nouvelles\/les-banques-alimentaires-reduisent-leurs-services-face-a-une-demande-croissante\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Food banks cut services as surging demand outpaces resources\" \/>\n<meta property=\"og:description\" content=\"A new report by Feed Ontario reveals that food banks are cutting service amid record-high demand and resource shortages.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/feedontario.ca\/fr\/nouvelles\/les-banques-alimentaires-reduisent-leurs-services-face-a-une-demande-croissante\/\" \/>\n<meta property=\"og:site_name\" content=\"Feed Ontario\" \/>\n<meta property=\"og:image\" content=\"https:\/\/feedontario.ca\/wp-content\/uploads\/2024\/11\/HR24_Cover-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/feedontario.ca\\\/news\\\/food-banks-cut-services-amid-surging-demand\\\/\",\"url\":\"https:\\\/\\\/feedontario.ca\\\/news\\\/food-banks-cut-services-amid-surging-demand\\\/\",\"name\":\"Food banks cut services as surging demand outpaces resources\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/feedontario.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/feedontario.ca\\\/news\\\/food-banks-cut-services-amid-surging-demand\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/feedontario.ca\\\/news\\\/food-banks-cut-services-amid-surging-demand\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/feedontario.ca\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/HR24_Cover-1.jpg\",\"datePublished\":\"2024-12-02T01:00:19+00:00\",\"description\":\"A new report by Feed Ontario reveals that food banks are cutting service amid record-high demand and resource shortages.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/feedontario.ca\\\/news\\\/food-banks-cut-services-amid-surging-demand\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/feedontario.ca\\\/news\\\/food-banks-cut-services-amid-surging-demand\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/feedontario.ca\\\/news\\\/food-banks-cut-services-amid-surging-demand\\\/#primaryimage\",\"url\":\"https:\\\/\\\/feedontario.ca\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/HR24_Cover-1.jpg\",\"contentUrl\":\"https:\\\/\\\/feedontario.ca\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/HR24_Cover-1.jpg\",\"width\":1080,\"height\":1080,\"caption\":\"Hunger Report cover\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/feedontario.ca\\\/news\\\/food-banks-cut-services-amid-surging-demand\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/feedontario.ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Food banks are cutting services as surging demand outpaces resources\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/feedontario.ca\\\/#website\",\"url\":\"https:\\\/\\\/feedontario.ca\\\/\",\"name\":\"Feed Ontario\",\"description\":\"Uniting food banks, industry partners, and local communities in our work to end hunger and poverty\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/feedontario.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les banques alimentaires r\u00e9duisent leurs services, car la demande croissante d\u00e9passe les ressources.","description":"Un nouveau rapport de Feed Ontario r\u00e9v\u00e8le que les banques alimentaires r\u00e9duisent leurs services dans un contexte de demande record et de p\u00e9nurie de ressources.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/feedontario.ca\/fr\/nouvelles\/les-banques-alimentaires-reduisent-leurs-services-face-a-une-demande-croissante\/","og_locale":"fr_CA","og_type":"article","og_title":"Food banks cut services as surging demand outpaces resources","og_description":"A new report by Feed Ontario reveals that food banks are cutting service amid record-high demand and resource shortages.","og_url":"https:\/\/feedontario.ca\/fr\/nouvelles\/les-banques-alimentaires-reduisent-leurs-services-face-a-une-demande-croissante\/","og_site_name":"Feed Ontario","og_image":[{"width":1080,"height":1080,"url":"https:\/\/feedontario.ca\/wp-content\/uploads\/2024\/11\/HR24_Cover-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/feedontario.ca\/news\/food-banks-cut-services-amid-surging-demand\/","url":"https:\/\/feedontario.ca\/news\/food-banks-cut-services-amid-surging-demand\/","name":"Les banques alimentaires r\u00e9duisent leurs services, car la demande croissante d\u00e9passe les ressources.","isPartOf":{"@id":"https:\/\/feedontario.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/feedontario.ca\/news\/food-banks-cut-services-amid-surging-demand\/#primaryimage"},"image":{"@id":"https:\/\/feedontario.ca\/news\/food-banks-cut-services-amid-surging-demand\/#primaryimage"},"thumbnailUrl":"https:\/\/feedontario.ca\/wp-content\/uploads\/2024\/11\/HR24_Cover-1.jpg","datePublished":"2024-12-02T01:00:19+00:00","description":"Un nouveau rapport de Feed Ontario r\u00e9v\u00e8le que les banques alimentaires r\u00e9duisent leurs services dans un contexte de demande record et de p\u00e9nurie de ressources.","breadcrumb":{"@id":"https:\/\/feedontario.ca\/news\/food-banks-cut-services-amid-surging-demand\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/feedontario.ca\/news\/food-banks-cut-services-amid-surging-demand\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/feedontario.ca\/news\/food-banks-cut-services-amid-surging-demand\/#primaryimage","url":"https:\/\/feedontario.ca\/wp-content\/uploads\/2024\/11\/HR24_Cover-1.jpg","contentUrl":"https:\/\/feedontario.ca\/wp-content\/uploads\/2024\/11\/HR24_Cover-1.jpg","width":1080,"height":1080,"caption":"Hunger Report cover"},{"@type":"BreadcrumbList","@id":"https:\/\/feedontario.ca\/news\/food-banks-cut-services-amid-surging-demand\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/feedontario.ca\/"},{"@type":"ListItem","position":2,"name":"Food banks are cutting services as surging demand outpaces resources"}]},{"@type":"WebSite","@id":"https:\/\/feedontario.ca\/#website","url":"https:\/\/feedontario.ca\/","name":"Nourrir l'Ontario","description":"Unir les banques alimentaires, les partenaires industriels et les communaut\u00e9s locales dans notre travail pour \u00e9radiquer la faim et la pauvret\u00e9.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/feedontario.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"}]}},"_links":{"self":[{"href":"https:\/\/feedontario.ca\/fr\/wp-json\/wp\/v2\/news\/46252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/feedontario.ca\/fr\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/feedontario.ca\/fr\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/feedontario.ca\/fr\/wp-json\/wp\/v2\/media\/46253"}],"wp:attachment":[{"href":"https:\/\/feedontario.ca\/fr\/wp-json\/wp\/v2\/media?parent=46252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}